{"id":2123,"date":"2019-01-18T15:53:11","date_gmt":"2019-01-18T20:53:11","guid":{"rendered":"https:\/\/ambbogota.esteri.it\/news\/dall_ambasciata\/2019\/01\/messaggio-del-minisitro-moavero\/"},"modified":"2019-01-18T15:53:11","modified_gmt":"2019-01-18T20:53:11","slug":"messaggio-del-minisitro-moavero","status":"publish","type":"post","link":"https:\/\/ambbogota.esteri.it\/it\/news\/dall_ambasciata\/2019\/01\/messaggio-del-minisitro-moavero\/","title":{"rendered":"Messaggio del Minisitro Moavero Milanesi per l\u2019attentato alla scuola \u201cGeneral Santander\u201d di Bogot\u00e0"},"content":{"rendered":"<p>Il Ministro degli Affari Esteri e della Cooperazione Internazionale d&#8217;Italia, Enzo Moavero Milanesi, desidera esprimere le pi\u00f9 sentite condoglianze alle famiglie delle vittime e la vicinanza ai feriti del gravissimo attentato di questa mattina presso la Scuola di Polizia &#8220;General Santander&#8221; di Bogot\u00e0, che condanna nella maniera pi\u00f9 ferma.<\/p>\n","protected":false},"excerpt":{"rendered":"Il Ministro degli Affari Esteri e della Cooperazione Internazionale d&#8217;Italia, Enzo Moavero Milanesi, desidera esprimere le pi\u00f9 sentite condoglianze alle famiglie delle vittime e la vicinanza ai feriti del gravissimo attentato di questa mattina presso la Scuola di Polizia &#8220;General Santander&#8221; di Bogot\u00e0, che condanna nella maniera pi\u00f9 ferma.","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-2123","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=2123"}],"version-history":[{"count":0,"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2123\/revisions"}],"wp:attachment":[{"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=2123"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=2123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}