{"id":2129,"date":"2019-01-10T17:34:40","date_gmt":"2019-01-10T22:34:40","guid":{"rendered":"https:\/\/ambbogota.esteri.it\/news\/dall_ambasciata\/2019\/01\/nuove-norme-in-materia-di-cittadinanza\/"},"modified":"2019-01-10T17:34:40","modified_gmt":"2019-01-10T22:34:40","slug":"nuove-norme-in-materia-di-cittadinanza","status":"publish","type":"post","link":"https:\/\/ambbogota.esteri.it\/it\/news\/dall_ambasciata\/2019\/01\/nuove-norme-in-materia-di-cittadinanza\/","title":{"rendered":"Nuove norme in materia di cittadinanza, con riguardo alla naturalizzazione per matrimonio con cittadino italiano"},"content":{"rendered":"<p>In data 4 dicembre 2018 e\u2019 stato introdotto l&#8217;art. 9.1 alla Legge n. 91 del 5 febbraio 1992, che regola le modalit\u00e0 di acquisizione della cittadinanza italiana.<\/p>\n<p>Il nuovo articolo prevede il <strong>possesso di un&#8217;adeguata conoscenza della lingua italiana, non inferiore al livello B1<\/strong> del Quadro comune di riferimento per la conoscenza delle lingue, quale condizione per il riconoscimento della cittadinanza ai sensi dei seguenti articoli della suddetta legge: art. 5, naturalizzazione per matrimonio con cittadino italiano e art. 9, concessione della cittadinanza.<\/p>\n<p>L&#8217;accertamento della conoscenza della lingua va effettuato al momento della presentazione dell\u2019istanza attraverso l&#8217;acquisizione da parte di questa Ambasciata di:<\/p>\n<p>&#8211; Un titolo di studio rilasciato da un istituto italiano di istruzione pubblico o da un istituto paritario; o<\/p>\n<p>&#8211; Una certificazione rilasciata da un ente certificatore.<\/p>\n<p>Al momento possono considerarsi enti certificatori, appartenenti al sistema di Certificazione della Lingua Italiana di Qualita\u2019:<\/p>\n<p>&#8211; L&#8217;Universita&#8217; per stranieri di Siena<\/p>\n<p>&#8211; L&#8217;Universita&#8217; per stranieri di Perugia<\/p>\n<p>&#8211; L&#8217;Universita&#8217; Roma Tre<\/p>\n<p>&#8211; La Societa\u2019 Dante Alighieri in collaborazione con l\u2019Istituto Italiano di Cultura\u00a0<\/p>\n<p><a href=\"https:\/\/iicbogota.esteri.it\/iic_bogota\/it\/imparare_italiano\/certificazioni\/\">https:\/\/iicbogota.esteri.it\/iic_bogota\/it\/imparare_italiano\/certificazioni\/<\/a>\u00a0<\/p>\n<p>Si conferma inoltre che l&#8217;importo del contributo dovuto al Ministero dell&#8217;Interno per tali pratiche <strong>passa da 200,00 \u20ac a \u20ac 250,00<\/strong>, ai sensi del nuovo art. 9-bis della legge 5 febbraio 1992, n. 91.<\/p>\n<p>Le modalita\u2019 di versamento del contributo rimangono le stesse.<\/p>\n<p>Per non incorrere nel rigetto dell\u2019istanza si raccomanda di inserire la certificazione linguistica richiesta.<\/p>\n","protected":false},"excerpt":{"rendered":"In data 4 dicembre 2018 e\u2019 stato introdotto l&#8217;art. 9.1 alla Legge n. 91 del 5 febbraio 1992, che regola le modalit\u00e0 di acquisizione della cittadinanza italiana. Il nuovo articolo prevede il possesso di un&#8217;adeguata conoscenza della lingua italiana, non inferiore al livello B1 del Quadro comune di riferimento per la conoscenza delle lingue, quale [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-2129","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=2129"}],"version-history":[{"count":0,"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2129\/revisions"}],"wp:attachment":[{"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=2129"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=2129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}