{"id":2133,"date":"2019-01-04T15:00:55","date_gmt":"2019-01-04T20:00:55","guid":{"rendered":"https:\/\/ambbogota.esteri.it\/news\/dall_ambasciata\/2019\/01\/presemntazione-delle-lettere-credenziali\/"},"modified":"2019-01-04T15:00:55","modified_gmt":"2019-01-04T20:00:55","slug":"presemntazione-delle-lettere-credenziali","status":"publish","type":"post","link":"https:\/\/ambbogota.esteri.it\/it\/news\/dall_ambasciata\/2019\/01\/presemntazione-delle-lettere-credenziali\/","title":{"rendered":"Presentazione delle Lettere Credenziali del nuovo Ambasciatore della Repubblica d&#8217;Italia in Colombia"},"content":{"rendered":"<p>Il 19 dicembre 2018 il nuovo Ambasciatore della Repubblica d\u2019Italia in Colombia, Gherardo Amaduzzi, ha presentato le Lettere Credenziali al Presidente della Repubblica di Colombia Iv\u00e1n Duque M\u00e1rquez.<\/p>\n<p>L\u2019Ambasciatore Amaduzzi, sottolineando di essere onorato di rappresentare l\u2019Italia in Colombia, ha confermato al Presidente Duque il convinto sostegno italiano al processo di pace in Colombia e la volont\u00e0 di rafforzare le relazioni bilaterali in tutti i settori.<\/p>\n","protected":false},"excerpt":{"rendered":"Il 19 dicembre 2018 il nuovo Ambasciatore della Repubblica d\u2019Italia in Colombia, Gherardo Amaduzzi, ha presentato le Lettere Credenziali al Presidente della Repubblica di Colombia Iv\u00e1n Duque M\u00e1rquez. L\u2019Ambasciatore Amaduzzi, sottolineando di essere onorato di rappresentare l\u2019Italia in Colombia, ha confermato al Presidente Duque il convinto sostegno italiano al processo di pace in Colombia e [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-2133","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=2133"}],"version-history":[{"count":0,"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2133\/revisions"}],"wp:attachment":[{"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=2133"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambbogota.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=2133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}